{"id":7327,"date":"2022-06-24T09:34:36","date_gmt":"2022-06-24T07:34:36","guid":{"rendered":"https:\/\/18.events\/?p=7327"},"modified":"2022-06-27T09:36:05","modified_gmt":"2022-06-27T07:36:05","slug":"une-semaine-un-golf-2","status":"publish","type":"post","link":"https:\/\/18.events\/pt-pt\/une-semaine-un-golf-2\/","title":{"rendered":"UNE SEMAINE, UN GOLF !"},"content":{"rendered":"<p>Cette semaine, nous vous proposons de d\u00e9couvrir le Golf De Montpellier Massane , golf r\u00e9f\u00e9rence en Occitanie.<br \/>\nLe golf a vu na\u00eetre et progresser de nombreux joueuses et joueurs qui aujourd\u2019hui \u00e9voluent au plus haut niveau mondial. Un golf pour tous et adapt\u00e9 \u00e0 chacun ! \u26f3\ufe0f<br \/>\nLors de votre partie, vous pourrez profiter de l&#8217;installation #Wininone sur le Trou n\u00b011 et peut-\u00eatre, vous envoler vers la RyderCup ! \ud83c\udfc6<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette semaine, nous vous proposons de d\u00e9couvrir le Golf De Montpellier Massane , golf r\u00e9f\u00e9rence en Occitanie. Le golf a vu na\u00eetre et progresser de nombreux joueuses et joueurs qui aujourd\u2019hui \u00e9voluent au plus haut niveau mondial. Un golf pour tous et adapt\u00e9 \u00e0 chacun ! \u26f3\ufe0f Lors de votre partie, vous pourrez profiter de [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":7328,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-7327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-18events","category-wininone"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNE SEMAINE, UN GOLF ! | Wininone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/18.events\/une-semaine-un-golf-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNE SEMAINE, UN GOLF ! | Wininone\" \/>\n<meta property=\"og:description\" content=\"Cette semaine, nous vous proposons de d\u00e9couvrir le Golf De Montpellier Massane , golf r\u00e9f\u00e9rence en Occitanie. Le golf a vu na\u00eetre et progresser de nombreux joueuses et joueurs qui aujourd\u2019hui \u00e9voluent au plus haut niveau mondial. Un golf pour tous et adapt\u00e9 \u00e0 chacun ! \u26f3\ufe0f Lors de votre partie, vous pourrez profiter de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/18.events\/une-semaine-un-golf-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Wininone\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-24T07:34:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-27T07:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/18.events\/wp-content\/uploads\/2022\/06\/289752153_566926024796618_4780320165242572793_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1221\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"No\u00e9mie Hookipa-\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9mie Hookipa-\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/\"},\"author\":{\"name\":\"No\u00e9mie Hookipa-\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/70fe8d1e0956cf728380a7ae5b9cc64e\"},\"headline\":\"UNE SEMAINE, UN GOLF !\",\"datePublished\":\"2022-06-24T07:34:36+00:00\",\"dateModified\":\"2022-06-27T07:36:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/\"},\"wordCount\":78,\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/289752153_566926024796618_4780320165242572793_n.jpg\",\"articleSection\":[\"18events\",\"WinInOne\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/\",\"name\":\"UNE SEMAINE, UN GOLF ! | Wininone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/289752153_566926024796618_4780320165242572793_n.jpg\",\"datePublished\":\"2022-06-24T07:34:36+00:00\",\"dateModified\":\"2022-06-27T07:36:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/289752153_566926024796618_4780320165242572793_n.jpg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/289752153_566926024796618_4780320165242572793_n.jpg\",\"width\":1221,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/18.events\\\/une-semaine-un-golf-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNE SEMAINE, UN GOLF !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/18.events\\\/#website\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"name\":\"Wininone\",\"description\":\"Cr\u00e9ateur de challenges pour golfeurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/18.events\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/18.events\\\/#organization\",\"name\":\"18.events\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"18.events\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/70fe8d1e0956cf728380a7ae5b9cc64e\",\"name\":\"No\u00e9mie Hookipa-\",\"url\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/author\\\/noemie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNE SEMAINE, UN GOLF ! | Wininone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/18.events\/une-semaine-un-golf-2\/","og_locale":"pt_PT","og_type":"article","og_title":"UNE SEMAINE, UN GOLF ! | Wininone","og_description":"Cette semaine, nous vous proposons de d\u00e9couvrir le Golf De Montpellier Massane , golf r\u00e9f\u00e9rence en Occitanie. Le golf a vu na\u00eetre et progresser de nombreux joueuses et joueurs qui aujourd\u2019hui \u00e9voluent au plus haut niveau mondial. Un golf pour tous et adapt\u00e9 \u00e0 chacun ! \u26f3\ufe0f Lors de votre partie, vous pourrez profiter de [&hellip;]","og_url":"https:\/\/18.events\/une-semaine-un-golf-2\/","og_site_name":"Wininone","article_published_time":"2022-06-24T07:34:36+00:00","article_modified_time":"2022-06-27T07:36:05+00:00","og_image":[{"width":1221,"height":640,"url":"https:\/\/18.events\/wp-content\/uploads\/2022\/06\/289752153_566926024796618_4780320165242572793_n.jpg","type":"image\/jpeg"}],"author":"No\u00e9mie Hookipa-","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"No\u00e9mie Hookipa-"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/18.events\/une-semaine-un-golf-2\/#article","isPartOf":{"@id":"https:\/\/18.events\/une-semaine-un-golf-2\/"},"author":{"name":"No\u00e9mie Hookipa-","@id":"https:\/\/18.events\/#\/schema\/person\/70fe8d1e0956cf728380a7ae5b9cc64e"},"headline":"UNE SEMAINE, UN GOLF !","datePublished":"2022-06-24T07:34:36+00:00","dateModified":"2022-06-27T07:36:05+00:00","mainEntityOfPage":{"@id":"https:\/\/18.events\/une-semaine-un-golf-2\/"},"wordCount":78,"publisher":{"@id":"https:\/\/18.events\/#organization"},"image":{"@id":"https:\/\/18.events\/une-semaine-un-golf-2\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2022\/06\/289752153_566926024796618_4780320165242572793_n.jpg","articleSection":["18events","WinInOne"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/18.events\/une-semaine-un-golf-2\/","url":"https:\/\/18.events\/une-semaine-un-golf-2\/","name":"UNE SEMAINE, UN GOLF ! | Wininone","isPartOf":{"@id":"https:\/\/18.events\/#website"},"primaryImageOfPage":{"@id":"https:\/\/18.events\/une-semaine-un-golf-2\/#primaryimage"},"image":{"@id":"https:\/\/18.events\/une-semaine-un-golf-2\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2022\/06\/289752153_566926024796618_4780320165242572793_n.jpg","datePublished":"2022-06-24T07:34:36+00:00","dateModified":"2022-06-27T07:36:05+00:00","breadcrumb":{"@id":"https:\/\/18.events\/une-semaine-un-golf-2\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/18.events\/une-semaine-un-golf-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/18.events\/une-semaine-un-golf-2\/#primaryimage","url":"https:\/\/18.events\/wp-content\/uploads\/2022\/06\/289752153_566926024796618_4780320165242572793_n.jpg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2022\/06\/289752153_566926024796618_4780320165242572793_n.jpg","width":1221,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/18.events\/une-semaine-un-golf-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/18.events\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"UNE SEMAINE, UN GOLF !"}]},{"@type":"WebSite","@id":"https:\/\/18.events\/#website","url":"https:\/\/18.events\/","name":"Wininone","description":"Cr\u00e9ateur de challenges pour golfeurs","publisher":{"@id":"https:\/\/18.events\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/18.events\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/18.events\/#organization","name":"18.events","url":"https:\/\/18.events\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/18.events\/#\/schema\/logo\/image\/","url":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","width":1,"height":1,"caption":"18.events"},"image":{"@id":"https:\/\/18.events\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/18.events\/#\/schema\/person\/70fe8d1e0956cf728380a7ae5b9cc64e","name":"No\u00e9mie Hookipa-","url":"https:\/\/18.events\/pt-pt\/author\/noemie\/"}]}},"fimg_url":"https:\/\/18.events\/wp-content\/uploads\/2022\/06\/289752153_566926024796618_4780320165242572793_n.jpg","_links":{"self":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts\/7327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/comments?post=7327"}],"version-history":[{"count":0,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts\/7327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/media\/7328"}],"wp:attachment":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/media?parent=7327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/categories?post=7327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/tags?post=7327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}