{"id":5274,"date":"2022-01-06T12:10:15","date_gmt":"2022-01-06T11:10:15","guid":{"rendered":"https:\/\/18.events\/?p=5274"},"modified":"2022-01-06T17:10:53","modified_gmt":"2022-01-06T16:10:53","slug":"le-voyage-des-gagnants","status":"publish","type":"post","link":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/","title":{"rendered":"Le voyage des gagnants"},"content":{"rendered":"<p>\ud83d\udeebLes gagnants sont mont\u00e9s dans l&#8217;avion ! \ud83c\udfdd\u26f1<br \/>\nOn les attend avec impatience ! \ud83c\udfcc\ufe0f\ud83c\udf34<\/p>\n<p>\ud83d\udcf8Photo de groupe \ud83d\udcf8<br \/>\nC&#8217;\u00e9tait juste avant l&#8217;embarquement des gagnants Wininone pour la #RaceToHawaii&#8230; \ud83d\udeeb\ud83d\ude0d<br \/>\nDans quelques heures, ils seront avec nous sur la plage de waikiki ! \ud83c\udf34\u23f3\ud83c\udfcc<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udeebLes gagnants sont mont\u00e9s dans l&#8217;avion ! \ud83c\udfdd\u26f1 On les attend avec impatience ! \ud83c\udfcc\ufe0f\ud83c\udf34 \ud83d\udcf8Photo de groupe \ud83d\udcf8 C&#8217;\u00e9tait juste avant l&#8217;embarquement des gagnants Wininone pour la #RaceToHawaii&#8230; \ud83d\udeeb\ud83d\ude0d Dans quelques heures, ils seront avec nous sur la plage de waikiki ! \ud83c\udf34\u23f3\ud83c\udfcc<\/p>\n","protected":false},"author":64,"featured_media":5275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-5274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wininone"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le voyage des gagnants | Wininone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le voyage des gagnants | Wininone\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udeebLes gagnants sont mont\u00e9s dans l&#8217;avion ! \ud83c\udfdd\u26f1 On les attend avec impatience ! \ud83c\udfcc\ufe0f\ud83c\udf34 \ud83d\udcf8Photo de groupe \ud83d\udcf8 C&#8217;\u00e9tait juste avant l&#8217;embarquement des gagnants Wininone pour la #RaceToHawaii&#8230; \ud83d\udeeb\ud83d\ude0d Dans quelques heures, ils seront avec nous sur la plage de waikiki ! \ud83c\udf34\u23f3\ud83c\udfcc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/\" \/>\n<meta property=\"og:site_name\" content=\"Wininone\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-06T11:10:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-06T16:10:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/18.events\/wp-content\/uploads\/2022\/01\/271434668_462298815259340_2597156773766732155_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"No\u00e9mie Hookipa-\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9mie Hookipa-\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/\"},\"author\":{\"name\":\"No\u00e9mie Hookipa-\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/70fe8d1e0956cf728380a7ae5b9cc64e\"},\"headline\":\"Le voyage des gagnants\",\"datePublished\":\"2022-01-06T11:10:15+00:00\",\"dateModified\":\"2022-01-06T16:10:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/\"},\"wordCount\":57,\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/271434668_462298815259340_2597156773766732155_n.jpg\",\"articleSection\":[\"WinInOne\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/\",\"name\":\"Le voyage des gagnants | Wininone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/271434668_462298815259340_2597156773766732155_n.jpg\",\"datePublished\":\"2022-01-06T11:10:15+00:00\",\"dateModified\":\"2022-01-06T16:10:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/271434668_462298815259340_2597156773766732155_n.jpg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/271434668_462298815259340_2597156773766732155_n.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/le-voyage-des-gagnants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le voyage des gagnants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/18.events\\\/#website\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"name\":\"Wininone\",\"description\":\"Cr\u00e9ateur de challenges pour golfeurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/18.events\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/18.events\\\/#organization\",\"name\":\"18.events\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"18.events\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/70fe8d1e0956cf728380a7ae5b9cc64e\",\"name\":\"No\u00e9mie Hookipa-\",\"url\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/author\\\/noemie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le voyage des gagnants | Wininone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/","og_locale":"pt_PT","og_type":"article","og_title":"Le voyage des gagnants | Wininone","og_description":"\ud83d\udeebLes gagnants sont mont\u00e9s dans l&#8217;avion ! \ud83c\udfdd\u26f1 On les attend avec impatience ! \ud83c\udfcc\ufe0f\ud83c\udf34 \ud83d\udcf8Photo de groupe \ud83d\udcf8 C&#8217;\u00e9tait juste avant l&#8217;embarquement des gagnants Wininone pour la #RaceToHawaii&#8230; \ud83d\udeeb\ud83d\ude0d Dans quelques heures, ils seront avec nous sur la plage de waikiki ! \ud83c\udf34\u23f3\ud83c\udfcc","og_url":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/","og_site_name":"Wininone","article_published_time":"2022-01-06T11:10:15+00:00","article_modified_time":"2022-01-06T16:10:53+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/18.events\/wp-content\/uploads\/2022\/01\/271434668_462298815259340_2597156773766732155_n.jpg","type":"image\/jpeg"}],"author":"No\u00e9mie Hookipa-","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"No\u00e9mie Hookipa-"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/#article","isPartOf":{"@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/"},"author":{"name":"No\u00e9mie Hookipa-","@id":"https:\/\/18.events\/#\/schema\/person\/70fe8d1e0956cf728380a7ae5b9cc64e"},"headline":"Le voyage des gagnants","datePublished":"2022-01-06T11:10:15+00:00","dateModified":"2022-01-06T16:10:53+00:00","mainEntityOfPage":{"@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/"},"wordCount":57,"publisher":{"@id":"https:\/\/18.events\/#organization"},"image":{"@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2022\/01\/271434668_462298815259340_2597156773766732155_n.jpg","articleSection":["WinInOne"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/","url":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/","name":"Le voyage des gagnants | Wininone","isPartOf":{"@id":"https:\/\/18.events\/#website"},"primaryImageOfPage":{"@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/#primaryimage"},"image":{"@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2022\/01\/271434668_462298815259340_2597156773766732155_n.jpg","datePublished":"2022-01-06T11:10:15+00:00","dateModified":"2022-01-06T16:10:53+00:00","breadcrumb":{"@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/#primaryimage","url":"https:\/\/18.events\/wp-content\/uploads\/2022\/01\/271434668_462298815259340_2597156773766732155_n.jpg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2022\/01\/271434668_462298815259340_2597156773766732155_n.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/18.events\/pt-pt\/le-voyage-des-gagnants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/18.events\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Le voyage des gagnants"}]},{"@type":"WebSite","@id":"https:\/\/18.events\/#website","url":"https:\/\/18.events\/","name":"Wininone","description":"Cr\u00e9ateur de challenges pour golfeurs","publisher":{"@id":"https:\/\/18.events\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/18.events\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/18.events\/#organization","name":"18.events","url":"https:\/\/18.events\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/18.events\/#\/schema\/logo\/image\/","url":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","width":1,"height":1,"caption":"18.events"},"image":{"@id":"https:\/\/18.events\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/18.events\/#\/schema\/person\/70fe8d1e0956cf728380a7ae5b9cc64e","name":"No\u00e9mie Hookipa-","url":"https:\/\/18.events\/pt-pt\/author\/noemie\/"}]}},"fimg_url":"https:\/\/18.events\/wp-content\/uploads\/2022\/01\/271434668_462298815259340_2597156773766732155_n.jpg","_links":{"self":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts\/5274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/comments?post=5274"}],"version-history":[{"count":0,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts\/5274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/media\/5275"}],"wp:attachment":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/media?parent=5274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/categories?post=5274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/tags?post=5274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}