{"id":1840,"date":"2021-05-05T18:15:16","date_gmt":"2021-05-05T16:15:16","guid":{"rendered":"https:\/\/18.events\/?p=1840"},"modified":"2021-05-05T18:16:44","modified_gmt":"2021-05-05T16:16:44","slug":"alerte-second-trou-en-1-en-ariege","status":"publish","type":"post","link":"https:\/\/18.events\/pt-pt\/alerte-second-trou-en-1-en-ariege\/","title":{"rendered":"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE !"},"content":{"rendered":"<p>Nouveau Hole-in-One #Wininone \u26f3\ufe0fr\u00e9alis\u00e9 sur l&#8217;@ecogolfariege \ud83e\udd29! Christian joue avec les \u00e9l\u00e9ments ! Merci le rocher !\ud83d\ude01\ud83c\udf40 C&#8217;est le r\u00e9sultat qui compte comme on dit ! BRAVO !<br \/>\nEn route pour la #RaceToHawaii! \ud83c\udf34\ud83c\udf08#ALOHA !\ud83e\udd19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nouveau Hole-in-One #Wininone \u26f3\ufe0fr\u00e9alis\u00e9 sur l&#8217;@ecogolfariege \ud83e\udd29! Christian joue avec les \u00e9l\u00e9ments ! Merci le rocher !\ud83d\ude01\ud83c\udf40 C&#8217;est le r\u00e9sultat qui compte comme on dit ! BRAVO ! En route pour la #RaceToHawaii! \ud83c\udf34\ud83c\udf08#ALOHA !\ud83e\udd19<\/p>\n","protected":false},"author":3,"featured_media":1842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE ! | Wininone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE ! | Wininone\" \/>\n<meta property=\"og:description\" content=\"Nouveau Hole-in-One #Wininone \u26f3\ufe0fr\u00e9alis\u00e9 sur l&#8217;@ecogolfariege \ud83e\udd29! Christian joue avec les \u00e9l\u00e9ments ! Merci le rocher !\ud83d\ude01\ud83c\udf40 C&#8217;est le r\u00e9sultat qui compte comme on dit ! BRAVO ! En route pour la #RaceToHawaii! \ud83c\udf34\ud83c\udf08#ALOHA !\ud83e\udd19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/\" \/>\n<meta property=\"og:site_name\" content=\"Wininone\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-05T16:15:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-05T16:16:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/18.events\/wp-content\/uploads\/2021\/05\/Wininone-Ariege-1024x572.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Benoit Lemauf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benoit Lemauf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/\"},\"author\":{\"name\":\"Benoit Lemauf\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/2cdce47e753b919f02a9fa6f0b5aed1a\"},\"headline\":\"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE !\",\"datePublished\":\"2021-05-05T16:15:16+00:00\",\"dateModified\":\"2021-05-05T16:16:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/\"},\"wordCount\":49,\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Wininone-Ariege.png\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/\",\"name\":\"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE ! | Wininone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Wininone-Ariege.png\",\"datePublished\":\"2021-05-05T16:15:16+00:00\",\"dateModified\":\"2021-05-05T16:16:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/#primaryimage\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Wininone-Ariege.png\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Wininone-Ariege.png\",\"width\":2172,\"height\":1214},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/18.events\\\/es\\\/alerte-second-trou-en-1-en-ariege\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/18.events\\\/#website\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"name\":\"Wininone\",\"description\":\"Cr\u00e9ateur de challenges pour golfeurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/18.events\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/18.events\\\/#organization\",\"name\":\"18.events\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"18.events\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/2cdce47e753b919f02a9fa6f0b5aed1a\",\"name\":\"Benoit Lemauf\",\"url\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/author\\\/benoit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE ! | Wininone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/","og_locale":"pt_PT","og_type":"article","og_title":"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE ! | Wininone","og_description":"Nouveau Hole-in-One #Wininone \u26f3\ufe0fr\u00e9alis\u00e9 sur l&#8217;@ecogolfariege \ud83e\udd29! Christian joue avec les \u00e9l\u00e9ments ! Merci le rocher !\ud83d\ude01\ud83c\udf40 C&#8217;est le r\u00e9sultat qui compte comme on dit ! BRAVO ! En route pour la #RaceToHawaii! \ud83c\udf34\ud83c\udf08#ALOHA !\ud83e\udd19","og_url":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/","og_site_name":"Wininone","article_published_time":"2021-05-05T16:15:16+00:00","article_modified_time":"2021-05-05T16:16:44+00:00","og_image":[{"width":1024,"height":572,"url":"https:\/\/18.events\/wp-content\/uploads\/2021\/05\/Wininone-Ariege-1024x572.png","type":"image\/png"}],"author":"Benoit Lemauf","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Benoit Lemauf"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/#article","isPartOf":{"@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/"},"author":{"name":"Benoit Lemauf","@id":"https:\/\/18.events\/#\/schema\/person\/2cdce47e753b919f02a9fa6f0b5aed1a"},"headline":"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE !","datePublished":"2021-05-05T16:15:16+00:00","dateModified":"2021-05-05T16:16:44+00:00","mainEntityOfPage":{"@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/"},"wordCount":49,"publisher":{"@id":"https:\/\/18.events\/#organization"},"image":{"@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/05\/Wininone-Ariege.png","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/","url":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/","name":"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE ! | Wininone","isPartOf":{"@id":"https:\/\/18.events\/#website"},"primaryImageOfPage":{"@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/#primaryimage"},"image":{"@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/05\/Wininone-Ariege.png","datePublished":"2021-05-05T16:15:16+00:00","dateModified":"2021-05-05T16:16:44+00:00","breadcrumb":{"@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/#primaryimage","url":"https:\/\/18.events\/wp-content\/uploads\/2021\/05\/Wininone-Ariege.png","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/05\/Wininone-Ariege.png","width":2172,"height":1214},{"@type":"BreadcrumbList","@id":"https:\/\/18.events\/es\/alerte-second-trou-en-1-en-ariege\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/18.events\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"ALERTE ! SECOND TROU EN 1 EN ARI\u00c8GE !"}]},{"@type":"WebSite","@id":"https:\/\/18.events\/#website","url":"https:\/\/18.events\/","name":"Wininone","description":"Cr\u00e9ateur de challenges pour golfeurs","publisher":{"@id":"https:\/\/18.events\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/18.events\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/18.events\/#organization","name":"18.events","url":"https:\/\/18.events\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/18.events\/#\/schema\/logo\/image\/","url":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","width":1,"height":1,"caption":"18.events"},"image":{"@id":"https:\/\/18.events\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/18.events\/#\/schema\/person\/2cdce47e753b919f02a9fa6f0b5aed1a","name":"Benoit Lemauf","url":"https:\/\/18.events\/pt-pt\/author\/benoit\/"}]}},"fimg_url":"https:\/\/18.events\/wp-content\/uploads\/2021\/05\/Wininone-Ariege.png","_links":{"self":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts\/1840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/comments?post=1840"}],"version-history":[{"count":0,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts\/1840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/media\/1842"}],"wp:attachment":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/media?parent=1840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/categories?post=1840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/tags?post=1840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}