{"id":1429,"date":"2020-12-28T16:25:30","date_gmt":"2020-12-28T15:25:30","guid":{"rendered":"https:\/\/18.events\/?p=1429"},"modified":"2021-03-13T16:26:09","modified_gmt":"2021-03-13T15:26:09","slug":"bravo-laurent","status":"publish","type":"post","link":"https:\/\/18.events\/pt-pt\/bravo-laurent\/","title":{"rendered":"BRAVO LAURENT !"},"content":{"rendered":"<p>\ud83e\udd29CADEAU DE NO\u00cbL WININONE !\ud83e\udd73<br \/>\n100% de bonnes r\u00e9ponses ! Nos fans sont des sp\u00e9cialistes du #golf !\ud83c\udfcc<br \/>\n\ud83c\udf89\ud83c\udf81Bravo \u00e0 Laurent Mercier qui gagne un abonnement de 12 mois \u00e0 #wininone sur tous les golfs du r\u00e9seau !<br \/>\nNous vous contacterons par message priv\u00e9 dans la journ\u00e9e<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83e\udd29CADEAU DE NO\u00cbL WININONE !\ud83e\udd73 100% de bonnes r\u00e9ponses ! Nos fans sont des sp\u00e9cialistes du #golf !\ud83c\udfcc \ud83c\udf89\ud83c\udf81Bravo \u00e0 Laurent Mercier qui gagne un abonnement de 12 mois \u00e0 #wininone sur tous les golfs du r\u00e9seau ! Nous vous contacterons par message priv\u00e9 dans la journ\u00e9e<\/p>\n","protected":false},"author":3,"featured_media":1430,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BRAVO LAURENT ! | Wininone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/18.events\/bravo-laurent\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BRAVO LAURENT ! | Wininone\" \/>\n<meta property=\"og:description\" content=\"\ud83e\udd29CADEAU DE NO\u00cbL WININONE !\ud83e\udd73 100% de bonnes r\u00e9ponses ! Nos fans sont des sp\u00e9cialistes du #golf !\ud83c\udfcc \ud83c\udf89\ud83c\udf81Bravo \u00e0 Laurent Mercier qui gagne un abonnement de 12 mois \u00e0 #wininone sur tous les golfs du r\u00e9seau ! Nous vous contacterons par message priv\u00e9 dans la journ\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/18.events\/bravo-laurent\/\" \/>\n<meta property=\"og:site_name\" content=\"Wininone\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-28T15:25:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-13T15:26:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-BRAVO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1191\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Benoit Lemauf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benoit Lemauf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/\"},\"author\":{\"name\":\"Benoit Lemauf\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/2cdce47e753b919f02a9fa6f0b5aed1a\"},\"headline\":\"BRAVO LAURENT !\",\"datePublished\":\"2020-12-28T15:25:30+00:00\",\"dateModified\":\"2021-03-13T15:26:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/\"},\"wordCount\":51,\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WININONE-BRAVO.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/\",\"name\":\"BRAVO LAURENT ! | Wininone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WININONE-BRAVO.jpg\",\"datePublished\":\"2020-12-28T15:25:30+00:00\",\"dateModified\":\"2021-03-13T15:26:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WININONE-BRAVO.jpg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WININONE-BRAVO.jpg\",\"width\":1191,\"height\":624},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/18.events\\\/bravo-laurent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BRAVO LAURENT !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/18.events\\\/#website\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"name\":\"Wininone\",\"description\":\"Cr\u00e9ateur de challenges pour golfeurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/18.events\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/18.events\\\/#organization\",\"name\":\"18.events\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"18.events\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/2cdce47e753b919f02a9fa6f0b5aed1a\",\"name\":\"Benoit Lemauf\",\"url\":\"https:\\\/\\\/18.events\\\/pt-pt\\\/author\\\/benoit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BRAVO LAURENT ! | Wininone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/18.events\/bravo-laurent\/","og_locale":"pt_PT","og_type":"article","og_title":"BRAVO LAURENT ! | Wininone","og_description":"\ud83e\udd29CADEAU DE NO\u00cbL WININONE !\ud83e\udd73 100% de bonnes r\u00e9ponses ! Nos fans sont des sp\u00e9cialistes du #golf !\ud83c\udfcc \ud83c\udf89\ud83c\udf81Bravo \u00e0 Laurent Mercier qui gagne un abonnement de 12 mois \u00e0 #wininone sur tous les golfs du r\u00e9seau ! Nous vous contacterons par message priv\u00e9 dans la journ\u00e9e","og_url":"https:\/\/18.events\/bravo-laurent\/","og_site_name":"Wininone","article_published_time":"2020-12-28T15:25:30+00:00","article_modified_time":"2021-03-13T15:26:09+00:00","og_image":[{"width":1191,"height":624,"url":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-BRAVO.jpg","type":"image\/jpeg"}],"author":"Benoit Lemauf","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Benoit Lemauf"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/18.events\/bravo-laurent\/#article","isPartOf":{"@id":"https:\/\/18.events\/bravo-laurent\/"},"author":{"name":"Benoit Lemauf","@id":"https:\/\/18.events\/#\/schema\/person\/2cdce47e753b919f02a9fa6f0b5aed1a"},"headline":"BRAVO LAURENT !","datePublished":"2020-12-28T15:25:30+00:00","dateModified":"2021-03-13T15:26:09+00:00","mainEntityOfPage":{"@id":"https:\/\/18.events\/bravo-laurent\/"},"wordCount":51,"publisher":{"@id":"https:\/\/18.events\/#organization"},"image":{"@id":"https:\/\/18.events\/bravo-laurent\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-BRAVO.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/18.events\/bravo-laurent\/","url":"https:\/\/18.events\/bravo-laurent\/","name":"BRAVO LAURENT ! | Wininone","isPartOf":{"@id":"https:\/\/18.events\/#website"},"primaryImageOfPage":{"@id":"https:\/\/18.events\/bravo-laurent\/#primaryimage"},"image":{"@id":"https:\/\/18.events\/bravo-laurent\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-BRAVO.jpg","datePublished":"2020-12-28T15:25:30+00:00","dateModified":"2021-03-13T15:26:09+00:00","breadcrumb":{"@id":"https:\/\/18.events\/bravo-laurent\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/18.events\/bravo-laurent\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/18.events\/bravo-laurent\/#primaryimage","url":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-BRAVO.jpg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-BRAVO.jpg","width":1191,"height":624},{"@type":"BreadcrumbList","@id":"https:\/\/18.events\/bravo-laurent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/18.events\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"BRAVO LAURENT !"}]},{"@type":"WebSite","@id":"https:\/\/18.events\/#website","url":"https:\/\/18.events\/","name":"Wininone","description":"Cr\u00e9ateur de challenges pour golfeurs","publisher":{"@id":"https:\/\/18.events\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/18.events\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/18.events\/#organization","name":"18.events","url":"https:\/\/18.events\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/18.events\/#\/schema\/logo\/image\/","url":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","width":1,"height":1,"caption":"18.events"},"image":{"@id":"https:\/\/18.events\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/18.events\/#\/schema\/person\/2cdce47e753b919f02a9fa6f0b5aed1a","name":"Benoit Lemauf","url":"https:\/\/18.events\/pt-pt\/author\/benoit\/"}]}},"fimg_url":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-BRAVO.jpg","_links":{"self":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts\/1429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/comments?post=1429"}],"version-history":[{"count":0,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/posts\/1429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/media\/1430"}],"wp:attachment":[{"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/media?parent=1429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/categories?post=1429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/18.events\/pt-pt\/wp-json\/wp\/v2\/tags?post=1429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}