{"id":1351,"date":"2020-07-28T16:08:38","date_gmt":"2020-07-28T14:08:38","guid":{"rendered":"https:\/\/18.events\/?p=1351"},"modified":"2021-03-13T16:09:25","modified_gmt":"2021-03-13T15:09:25","slug":"question-du-jour","status":"publish","type":"post","link":"https:\/\/18.events\/en\/question-du-jour\/","title":{"rendered":"QUESTION DU JOUR !"},"content":{"rendered":"<p>\ud83d\udce3Wininone sur l&#8217;European Tour !!\ud83d\udcaa\u26f3\ufe0f<br \/>\nQuel joueur fran\u00e7ais nous fait l&#8217;honneur d&#8217;arborer sur son sac le logo Wininone cette saison ?\ud83e\udd70<br \/>\nA vous de jouer !\ud83d\ude01<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udce3Wininone sur l&#8217;European Tour !!\ud83d\udcaa\u26f3\ufe0f Quel joueur fran\u00e7ais nous fait l&#8217;honneur d&#8217;arborer sur son sac le logo Wininone cette saison ?\ud83e\udd70 A vous de jouer !\ud83d\ude01<\/p>\n","protected":false},"author":3,"featured_media":1352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QUESTION DU JOUR ! | 18.events<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/18.events\/en\/question-du-jour\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QUESTION DU JOUR ! | 18.events\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udce3Wininone sur l&#8217;European Tour !!\ud83d\udcaa\u26f3\ufe0f Quel joueur fran\u00e7ais nous fait l&#8217;honneur d&#8217;arborer sur son sac le logo Wininone cette saison ?\ud83e\udd70 A vous de jouer !\ud83d\ude01\" \/>\n<meta property=\"og:url\" content=\"https:\/\/18.events\/en\/question-du-jour\/\" \/>\n<meta property=\"og:site_name\" content=\"18.events\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-28T14:08:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-13T15:09:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-PAVON.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"1057\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Benoit Lemauf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benoit Lemauf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/\"},\"author\":{\"name\":\"Benoit Lemauf\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/2cdce47e753b919f02a9fa6f0b5aed1a\"},\"headline\":\"QUESTION DU JOUR !\",\"datePublished\":\"2020-07-28T14:08:38+00:00\",\"dateModified\":\"2021-03-13T15:09:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/\"},\"wordCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WININONE-PAVON.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/\",\"name\":\"QUESTION DU JOUR ! | 18.events\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/18.events\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WININONE-PAVON.jpg\",\"datePublished\":\"2020-07-28T14:08:38+00:00\",\"dateModified\":\"2021-03-13T15:09:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WININONE-PAVON.jpg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WININONE-PAVON.jpg\",\"width\":750,\"height\":1057},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/18.events\\\/en\\\/question-du-jour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/18.events\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QUESTION DU JOUR !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/18.events\\\/#website\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"name\":\"18.events\",\"description\":\"Events creator around golf\",\"publisher\":{\"@id\":\"https:\\\/\\\/18.events\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/18.events\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/18.events\\\/#organization\",\"name\":\"18.events\",\"url\":\"https:\\\/\\\/18.events\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/18.events\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"18.events\"},\"image\":{\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/18.events\\\/#\\\/schema\\\/person\\\/2cdce47e753b919f02a9fa6f0b5aed1a\",\"name\":\"Benoit Lemauf\",\"url\":\"https:\\\/\\\/18.events\\\/en\\\/author\\\/benoit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QUESTION DU JOUR ! | 18.events","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/18.events\/en\/question-du-jour\/","og_locale":"en_US","og_type":"article","og_title":"QUESTION DU JOUR ! | 18.events","og_description":"\ud83d\udce3Wininone sur l&#8217;European Tour !!\ud83d\udcaa\u26f3\ufe0f Quel joueur fran\u00e7ais nous fait l&#8217;honneur d&#8217;arborer sur son sac le logo Wininone cette saison ?\ud83e\udd70 A vous de jouer !\ud83d\ude01","og_url":"https:\/\/18.events\/en\/question-du-jour\/","og_site_name":"18.events","article_published_time":"2020-07-28T14:08:38+00:00","article_modified_time":"2021-03-13T15:09:25+00:00","og_image":[{"width":750,"height":1057,"url":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-PAVON.jpg","type":"image\/jpeg"}],"author":"Benoit Lemauf","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Benoit Lemauf"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/18.events\/en\/question-du-jour\/#article","isPartOf":{"@id":"https:\/\/18.events\/en\/question-du-jour\/"},"author":{"name":"Benoit Lemauf","@id":"https:\/\/18.events\/#\/schema\/person\/2cdce47e753b919f02a9fa6f0b5aed1a"},"headline":"QUESTION DU JOUR !","datePublished":"2020-07-28T14:08:38+00:00","dateModified":"2021-03-13T15:09:25+00:00","mainEntityOfPage":{"@id":"https:\/\/18.events\/en\/question-du-jour\/"},"wordCount":30,"publisher":{"@id":"https:\/\/18.events\/#organization"},"image":{"@id":"https:\/\/18.events\/en\/question-du-jour\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-PAVON.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/18.events\/en\/question-du-jour\/","url":"https:\/\/18.events\/en\/question-du-jour\/","name":"QUESTION DU JOUR ! | 18.events","isPartOf":{"@id":"https:\/\/18.events\/#website"},"primaryImageOfPage":{"@id":"https:\/\/18.events\/en\/question-du-jour\/#primaryimage"},"image":{"@id":"https:\/\/18.events\/en\/question-du-jour\/#primaryimage"},"thumbnailUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-PAVON.jpg","datePublished":"2020-07-28T14:08:38+00:00","dateModified":"2021-03-13T15:09:25+00:00","breadcrumb":{"@id":"https:\/\/18.events\/en\/question-du-jour\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/18.events\/en\/question-du-jour\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/18.events\/en\/question-du-jour\/#primaryimage","url":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-PAVON.jpg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-PAVON.jpg","width":750,"height":1057},{"@type":"BreadcrumbList","@id":"https:\/\/18.events\/en\/question-du-jour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/18.events\/en\/"},{"@type":"ListItem","position":2,"name":"QUESTION DU JOUR !"}]},{"@type":"WebSite","@id":"https:\/\/18.events\/#website","url":"https:\/\/18.events\/","name":"18.events","description":"Events creator around golf","publisher":{"@id":"https:\/\/18.events\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/18.events\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/18.events\/#organization","name":"18.events","url":"https:\/\/18.events\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/18.events\/#\/schema\/logo\/image\/","url":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","contentUrl":"https:\/\/18.events\/wp-content\/uploads\/2021\/02\/logo.svg","width":1,"height":1,"caption":"18.events"},"image":{"@id":"https:\/\/18.events\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/18.events\/#\/schema\/person\/2cdce47e753b919f02a9fa6f0b5aed1a","name":"Benoit Lemauf","url":"https:\/\/18.events\/en\/author\/benoit\/"}]}},"fimg_url":"https:\/\/18.events\/wp-content\/uploads\/2021\/03\/WININONE-PAVON.jpg","_links":{"self":[{"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/posts\/1351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/comments?post=1351"}],"version-history":[{"count":0,"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/posts\/1351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/media\/1352"}],"wp:attachment":[{"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/media?parent=1351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/categories?post=1351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/18.events\/en\/wp-json\/wp\/v2\/tags?post=1351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}